{"id":22481,"date":"2024-02-14T15:14:10","date_gmt":"2024-02-14T14:14:10","guid":{"rendered":"https:\/\/www.somatra.ch\/?p=22481"},"modified":"2024-02-14T15:14:12","modified_gmt":"2024-02-14T14:14:12","slug":"simplifiez-vos-evenements-avec-nos-solutions-logistiques","status":"publish","type":"post","link":"https:\/\/www.somatra.ch\/en\/simplifiez-vos-evenements-avec-nos-solutions-logistiques\/","title":{"rendered":"Simplifiez vos \u00e9v\u00e9nements avec nos solutions logistiques"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vous recherchez un partenaire pour vous accompagner dans la logistique de votre op\u00e9ration \u00e9v\u00e9nementielle en Suisse ou \u00e0 l\u2019international&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chez SOMATRA, nous sommes l\u00e0 pour faciliter vos op\u00e9rations avec des solutions compl\u00e8tes qui prennent en charge chaque \u00e9tape de votre projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ensemble, nous \u00e9tablissons la feuille de route en fonction de vos volumes, de la s\u00e9curit\u00e9 n\u00e9cessaire, des contraintes mat\u00e9rielles et culturelles impos\u00e9es et nous vous proposons une logistique \u00e9v\u00e9nementielle sur-mesure qui comprend&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Un accompagnement dans les formalit\u00e9s douani\u00e8res<\/strong><\/li>\n\n\n\n<li><strong>Un moyen de transport adapt\u00e9 \u00e0 vos biens ou marchandises<\/strong><\/li>\n\n\n\n<li><strong>Montage et d\u00e9montage de vos \u00e9quipements<\/strong><\/li>\n\n\n\n<li><strong>Suivi en temps r\u00e9el<\/strong><\/li>\n\n\n\n<li><strong>Flexibilit\u00e9 et service client de qualit\u00e9<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Faites confiance \u00e0 SOMATRA pour simplifier votre prochain \u00e9v\u00e9nement. Contactez-nous d\u00e8s aujourd&#8217;hui au\u00a0<strong>022 827 38 38\u00a0<\/strong>ou \u00e0 notre adresse \u00e9lectronique\u00a0<a href=\"mailto:geneve@somatra.ch\" target=\"_blank\" rel=\"noreferrer noopener\">geneve@somatra.ch<\/a>\u00a0afin de discuter de vos projets et de vos besoins.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.somatra.ch\/wp-content\/uploads\/2024\/02\/somatra-truck-1024x576.jpg\" alt=\"\" class=\"wp-image-22482\" srcset=\"https:\/\/www.somatra.ch\/wp-content\/uploads\/2024\/02\/somatra-truck-1024x576.jpg 1024w, https:\/\/www.somatra.ch\/wp-content\/uploads\/2024\/02\/somatra-truck-300x169.jpg 300w, https:\/\/www.somatra.ch\/wp-content\/uploads\/2024\/02\/somatra-truck-768x432.jpg 768w, https:\/\/www.somatra.ch\/wp-content\/uploads\/2024\/02\/somatra-truck.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>SOMATRA facilite vos op\u00e9ration avec des solutions logistiques compl\u00e8tes \u00e0 chaque \u00e9tape de votre projet.<\/p>\n","protected":false},"author":2,"featured_media":22482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"Simplifiez vos \u00e9v\u00e9nements avec nos solutions logistiques - Somatra, entreprise de transport \u00e0 Gen\u00e8ve","description":"SOMATRA facilite vos op\u00e9ration avec des solutions logistiques compl\u00e8tes \u00e0 chaque \u00e9tape de votre projet."},"_slim_seo_primary_term_category":0,"_slim_seo_primary_term_post_tag":0,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-22481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus"],"_links":{"self":[{"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/posts\/22481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/comments?post=22481"}],"version-history":[{"count":0,"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/posts\/22481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/media\/22482"}],"wp:attachment":[{"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/media?parent=22481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/categories?post=22481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.somatra.ch\/en\/wp-json\/wp\/v2\/tags?post=22481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}